{"id":13074,"date":"2022-10-14T10:57:01","date_gmt":"2022-10-14T10:57:01","guid":{"rendered":"https:\/\/tecnol.es\/talento\/"},"modified":"2023-10-26T10:16:18","modified_gmt":"2023-10-26T10:16:18","slug":"talent","status":"publish","type":"page","link":"https:\/\/tecnol.es\/ca\/talent\/","title":{"rendered":"Talent"},"content":{"rendered":"[et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb admin_label=\u00bbHeader Section\u00bb _builder_version=\u00bb4.16&#8243; background_color=\u00bb#000000&#8243; custom_padding=\u00bb|||\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_header title=\u00bbTALENT\u00bb text_orientation=\u00bbcenter\u00bb header_fullscreen=\u00bbon\u00bb header_scroll_down=\u00bbon\u00bb scroll_down_icon=\u00bb%%2%%\u00bb scroll_down_icon_color=\u00bb#ffffff\u00bb background_overlay_color=\u00bbrgba(0,0,0,0.4)\u00bb content_max_width_last_edited=\u00bboff|desktop\u00bb admin_label=\u00bbContents\u00bb _builder_version=\u00bb4.19.2&#8243; title_level=\u00bbh4&#8243; title_font=\u00bb|||on|||||\u00bb title_text_align=\u00bbcenter\u00bb title_font_size=\u00bb80px\u00bb title_letter_spacing=\u00bb0.05em\u00bb title_line_height=\u00bb1.5em\u00bb content_font_size=\u00bb27px\u00bb subhead_font=\u00bb|600|||||||\u00bb subhead_font_size=\u00bb25px\u00bb subhead_line_height=\u00bb1.9em\u00bb background_color=\u00bb#14326B\u00bb background_image=\u00bbhttps:\/\/tecnol.es\/wp-content\/uploads\/2022\/11\/fondo-slider-1.jpg\u00bb parallax=\u00bbon\u00bb parallax_method=\u00bbon\u00bb custom_button_one=\u00bbon\u00bb button_one_text_size=\u00bb15px\u00bb button_one_bg_color=\u00bb#dca57d\u00bb button_one_border_width=\u00bb10px\u00bb button_one_border_color=\u00bb#dca57d\u00bb button_one_border_radius=\u00bb0px\u00bb button_one_letter_spacing=\u00bb3px\u00bb button_one_font=\u00bbOswald|||on|\u00bb button_one_use_icon=\u00bboff\u00bb animation_style=\u00bbfade\u00bb animation_starting_opacity=\u00bb50%\u00bb animation_speed_curve=\u00bbease-in\u00bb title_font_size_tablet=\u00bb60px\u00bb title_font_size_phone=\u00bb40px\u00bb title_font_size_last_edited=\u00bbon|tablet\u00bb button_one_border_color_hover=\u00bb#c99872&#8243; button_one_border_radius_hover=\u00bb0px\u00bb button_one_letter_spacing_hover=\u00bb3px\u00bb button_one_bg_color_hover=\u00bb#c99872&#8243; global_colors_info=\u00bb{}\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bbon\u00bb button_one_border_color__hover=\u00bb#c99872&#8243; button_two_border_color__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bbon\u00bb button_one_border_radius__hover=\u00bb0px\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bbon\u00bb button_one_letter_spacing__hover=\u00bb3px\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bbon\u00bb button_one_bg_color__hover=\u00bb#c99872&#8243; button_two_bg_color__hover_enabled=\u00bboff\u00bb]\n<p><strong><\/strong><em><strong>Uneix-te al #teamtecnol!<\/strong><\/em><\/p>\n[\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/tecnol.es\/wp-content\/uploads\/2022\/10\/t_tec.png\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_3,2_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]\n<h1 style=\"text-align: left;\">EL QUE ENS DEFINEIX<\/h1>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/tecnol.es\/wp-content\/uploads\/2022\/10\/device-repair-1A.png\u00bb title_text=\u00bbtrabajo-equipo\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/tecnol.es\/wp-content\/uploads\/2022\/11\/trabajo-equipo.jpg\u00bb width=\u00bb100%\u00bb module_alignment=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb31px|||||\u00bb global_colors_info=\u00bb{}\u00bb max_width__hover_enabled=\u00bbon|desktop\u00bb]\n<h4 style=\"text-align: justify;\">El nostre dia a dia ens apassiona<\/h4>\n<p style=\"text-align: justify;\">Tots sentim passi\u00f3 pel que fem. Ens sentim orgullosos del nostre treball i aix\u00f2 els nostres clients ho noten. Tenim l\u2019oportunitat d\u2019aprendre i formar-nos en all\u00f2 que realment ens apassiona i per aix\u00f2 som experts. Treballant a TECNOL tenim present que la nostra missi\u00f3 \u00e9s inspirar i guiar als nostres clients per fer-los la vida m\u00e9s f\u00e0cil a trav\u00e9s de la Innovaci\u00f3 i la Qualitat.<\/p>\n<p style=\"text-align: justify;\">[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb31px|||||\u00bb global_colors_info=\u00bb{}\u00bb max_width__hover_enabled=\u00bbon|desktop\u00bb]\n<h4 style=\"text-align: justify;\">Gaudim de treballar junts<\/h4>\n<p style=\"text-align: justify;\">Els que formem part de TECNOL ens divertim en el nostre dia a dia. \u00c9s important assegurar-nos que aix\u00ed sigui. Organitzem esdeveniments i jornades de portes obertes per gaudir junt amb les nostres fam\u00edlies, participem en tornejos esportius de futbol, p\u00e0del, b\u00e0squet o runnings socials i gaudim de convencions i festes d\u2019empresa on passem molt bons moments.<\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#f2f2f2&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb2_3,1_3&#8243; module_id=\u00bbtrabajar\u00bb _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb35px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb max_width__hover_enabled=\u00bbon|desktop\u00bb]\n<h4 style=\"text-align: justify;\">Treballar amb nosaltres<\/h4>\n<p style=\"text-align: justify;\">Perqu\u00e8 ens importen les persones. Perqu\u00e8 formem equips d&#8217;alt rendiment, compromesos amb l&#8217;excel\u00b7l\u00e8ncia i una visi\u00f3 \u00fanica de satisfacci\u00f3 al client.<\/p>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/tecnol.es\/wp-content\/uploads\/2022\/11\/device-repair-mask-04.png\u00bb title_text=\u00bbTecnol_rest\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/tecnol.es\/wp-content\/uploads\/2022\/10\/Tecnol_rest.jpg\u00bb background_position=\u00bbtop_right\u00bb width=\u00bb59%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,2_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/tecnol.es\/wp-content\/uploads\/2022\/11\/device-repair-mask-04.png\u00bb title_text=\u00bbdevice-repair-mask-04&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/tecnol.es\/wp-content\/uploads\/2022\/11\/miro_2021_v2.jpg\u00bb background_position=\u00bbtop_right\u00bb width=\u00bb59%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb58px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb max_width__hover_enabled=\u00bbon|desktop\u00bb]\n<h4 style=\"text-align: justify;\">Equip<\/h4>\n<p>Apostem pel treball en equip, per aix\u00f2 busquem persones que contagi\u00efn motivaci\u00f3, energia i actitud.<\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb2_3,1_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb44px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb max_width__hover_enabled=\u00bbon|desktop\u00bb]\n<h4 style=\"text-align: justify;\">Creixement personal<\/h4>\n<p>No pots ser un bon professional sense ser bona persona. Per nosaltres \u00e9s molt important que el creixement com professionals vagi agafat de la m\u00e0 del creixement com a persones. Nom\u00e9s aix\u00ed podem deixar empremta en el que fem.<\/p>\n<p>&nbsp;<\/p>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/tecnol.es\/wp-content\/uploads\/2022\/11\/device-repair-mask-04.png\u00bb title_text=\u00bbmanagers-visiting-storage-center-and-discussing-about-distribution-and-goals-for-next-year\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/tecnol.es\/wp-content\/uploads\/2022\/10\/managers-visiting-storage-center-and-discussing-about-distribution-and-goals-for-next-year.jpg\u00bb width=\u00bb59%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,2_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px|||||\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/tecnol.es\/wp-content\/uploads\/2022\/11\/device-repair-mask-04.png\u00bb title_text=\u00bbTecnolHealth_IndustryTools-e1635929908164&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/tecnol.es\/wp-content\/uploads\/2022\/10\/TecnolHealth_IndustryTools-e1635929908164.jpeg\u00bb width=\u00bb59%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb50px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb max_width__hover_enabled=\u00bbon|desktop\u00bb]\n<h4 style=\"text-align: justify;\">Creixement professional<\/h4>\n<p>Comptar\u00e0s amb projectes que et permetran posar en pr\u00e0ctica els teus coneixements i potenciaran les teves habilitats per convertir-te en el professional que sempre has volgut ser.<\/p>\n<p>&nbsp;<\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb2_3,1_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px|||||\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb51px|||||\u00bb global_colors_info=\u00bb{}\u00bb max_width__hover_enabled=\u00bbon|desktop\u00bb]\n<h4 style=\"text-align: justify;\">Innovaci\u00f3<\/h4>\n<p style=\"text-align: justify;\"><span>Estem enfocats a la innovaci\u00f3. Escoltem i promovem les propostes de tots els nostres equips. Tots som part del canvi.<\/span><span><\/span><span><\/span><\/p>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/tecnol.es\/wp-content\/uploads\/2022\/11\/device-repair-mask-04.png\u00bb title_text=\u00bbbuild1&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/tecnol.es\/wp-content\/uploads\/2022\/10\/build1.jpg\u00bb background_position=\u00bbtop_right\u00bb width=\u00bb59%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_slider _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb header_font_size=\u00bb25px\u00bb background_color=\u00bb#FFFFFF\u00bb height=\u00bb300px\u00bb height_tablet=\u00bb300px\u00bb height_phone=\u00bb500px\u00bb height_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb10px||10px||false|false\u00bb custom_padding_phone=\u00bb||||false|false\u00bb custom_padding_last_edited=\u00bboff|phone\u00bb auto=\u00bbon\u00bb auto_ignore_hover=\u00bbon\u00bb header_text_color_tablet=\u00bb\u00bb header_text_color_phone=\u00bb\u00bb header_text_color_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_slide heading=\u00bb%22Amb talent no es neix. El talent es fa%22&#8243; _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb header_text_color=\u00bb#14326B\u00bb header_font_size=\u00bb39px\u00bb body_font=\u00bb|700|on||||||\u00bb body_text_align=\u00bbright\u00bb body_text_color=\u00bb#14326B\u00bb background_color=\u00bb#FFFFFF\u00bb background_enable_color=\u00bbon\u00bb background_layout=\u00bblight\u00bb global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb]\n<p><span>Xavier Mart\u00ednez i Serra<\/span><\/p>\n[\/et_pb_slide][et_pb_slide heading=\u00bb%22El talent guanya partits, per\u00f2 el treball en equip guanya campionats%22&#8243; _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb header_text_color=\u00bb#14326B\u00bb header_font_size=\u00bb39px\u00bb body_font=\u00bb|700|on||||||\u00bb body_text_align=\u00bbright\u00bb body_text_color=\u00bb#14326B\u00bb background_color=\u00bb#FFFFFF\u00bb background_enable_color=\u00bbon\u00bb background_layout=\u00bblight\u00bb global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb]\n<p><span>Michael Jordan<\/span><\/p>\n<p><span>\u00a0<\/span><\/p>\n[\/et_pb_slide][et_pb_slide heading=\u00bb%22Tota gran aventura comen\u00e7a amb un salt al buit%22&#8243; _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb header_text_color=\u00bb#14326B\u00bb header_font_size=\u00bb39px\u00bb body_font=\u00bb|700|on||||||\u00bb body_text_align=\u00bbright\u00bb body_text_color=\u00bb#14326B\u00bb background_color=\u00bb#FFFFFF\u00bb background_enable_color=\u00bbon\u00bb background_layout=\u00bblight\u00bb global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb]\n<p><span>An\u00f3nimo<\/span><\/p>\n<p><span>\u00a0<\/span><\/p>\n<p><span>\u00a0<\/span><\/p>\n[\/et_pb_slide][et_pb_slide heading=\u00bb%22Forma la teva gent com si hagu\u00e9s de marxar. Tracta&#8217;ls perqu\u00e8 mai vulguin fer-ho%22&#8243; _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb header_text_color=\u00bb#14326B\u00bb header_font_size=\u00bb39px\u00bb body_font=\u00bb|700|on||||||\u00bb body_text_align=\u00bbright\u00bb body_text_color=\u00bb#14326B\u00bb background_color=\u00bb#FFFFFF\u00bb background_enable_color=\u00bbon\u00bb background_layout=\u00bblight\u00bb global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb]\n<p>Richard Branson<\/p>\n[\/et_pb_slide][\/et_pb_fullwidth_slider][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/tecnol.es\/wp-content\/uploads\/2022\/10\/t_tec.png\u00bb background_position=\u00bbtop_center\u00bb custom_padding=\u00bb20px||1px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row module_id=\u00bbunete\u00bb _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb10px||||false|false\u00bb custom_padding=\u00bb||0px|||\u00bb animation_style=\u00bbzoom\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb31px|||||\u00bb global_colors_info=\u00bb{}\u00bb max_width__hover_enabled=\u00bbon|desktop\u00bb]\n<h1 style=\"text-align: left;\">UNEIX-TE A NOSALTRES<\/h1>\n<p style=\"text-align: justify;\">A TECNOL trobar\u00e0s oportunitats reals de desenvolupament professional per cr\u00e9ixer dins de l\u2019organitzaci\u00f3 i assolir els teus objectius.<\/p>\n<p style=\"text-align: justify;\"><b>Volem con\u00e8ixer-te! ENVIA\u2019NS EL TEU CURR\u00cdCULUM I FORMA PART DEL NOSTRE EQUIP<\/b><\/p>\n[\/et_pb_text][et_pb_code _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f13379-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"13379\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ca\/wp-json\/wp\/v2\/pages\/13074#wpcf7-f13379-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"13379\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f13379-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"et_pb_contact\">\n\t<div class=\"et_pb_contact_form\">\n\t\t<p class=\"et_pb_contact_field et_pb_contact_field_half\"><span class=\"wpcf7-form-control-wrap\" data-name=\"Nombre\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"NOM*\" value=\"\" type=\"text\" name=\"Nombre\" \/><\/span>\n\t\t<\/p>\n\t\t<p class=\"et_pb_contact_field et_pb_contact_field_half et_pb_contact_field_last\"><span class=\"wpcf7-form-control-wrap\" data-name=\"Apellidos\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"COGNOMS\" value=\"\" type=\"text\" name=\"Apellidos\" \/><\/span>\n\t\t<\/p>\n\t\t<p class=\"et_pb_contact_field et_pb_contact_field_half\"><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"CORREU ELECTR\u00d2NIC*\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t<\/p>\n\t\t<p class=\"et_pb_contact_field et_pb_contact_field_half et_pb_contact_field_last\"><span class=\"wpcf7-form-control-wrap\" data-name=\"tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" placeholder=\"TEL\u00c8FON\" value=\"\" type=\"tel\" name=\"tel\" \/><\/span>\n\t\t<\/p>\n\t\t<p class=\"et_pb_contact_field et_pb_contact_field_last\"><span class=\"wpcf7-form-control-wrap\" data-name=\"mensaje\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"MISSATGE*\" name=\"mensaje\"><\/textarea><\/span>\n\t\t<\/p>\n\t\t<p class=\"et_pb_contact_field et_pb_contact_field_last\">Voleu adjuntar algun fitxer? (Formats doc,pdf,jpg) <!-- br--><span class=\"wpcf7-form-control-wrap\" data-name=\"adjunto\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".doc,.jpg,.pdf\" aria-invalid=\"false\" type=\"file\" name=\"adjunto\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"protecciondatos\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"protecciondatos\" value=\"1\" class=\"protect\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Accepto les <a href=\"https:\/\/tecnol.es\/nota-legal\/\" title=\"condicions generals\">condicions generals<\/a> i la <a href=\"https:\/\/tecnol.es\/politica-privacidad\/\" title=\"pol\u00edtica de privadesa\">pol\u00edtica de privadesa<\/a><\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<div class=\"et_contact_bottom_container\">\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner et_pb_contact_submit et_pb_button\" type=\"submit\" value=\"ENVIAR\" \/>\n\t<\/p>\n<\/div>\n<div class=\"et_contact_bottom_container\">\n\t<div class=\"et_pb_contact\">\n\t<\/div>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"243\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/et_pb_code][et_pb_contact_form disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb _unique_id=\u00bb0bfd46c3-70ac-49ee-bead-dca635f5e5f7&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#14326B\u00bb button_bg_color=\u00bb#FFFFFF\u00bb button_border_radius=\u00bb100px\u00bb custom_margin=\u00bb49px||||false|false\u00bb disabled=\u00bbon\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_contact_field field_id=\u00bbName\u00bb field_title=\u00bbNOMBRE*\u00bb _builder_version=\u00bb4.18.0&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbApellidos\u00bb field_title=\u00bbAPELLIDOS\u00bb field_type=\u00bbemail\u00bb _builder_version=\u00bb4.18.0&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbCorreo_Electr\u00f3nico\u00bb field_title=\u00bbCORREO ELECTR\u00d3NICO\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbTel\u00e9fono\u00bb field_title=\u00bbTEL\u00c9FONO\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbMessage\u00bb field_title=\u00bbMENSAJE\u00bb field_type=\u00bbtext\u00bb fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.18.0&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_video src=\u00bbhttps:\/\/youtu.be\/hC7FMZMB2OU\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb58%\u00bb module_alignment=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_video][et_pb_code admin_label=\u00bbSEO\u00bb _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<span class=\"collapseomatic \" id=\"id6a987ab80db91\"  tabindex=\"0\" title=\"\"    ><\/span><div id=\"target-id6a987ab80db91\" class=\"collapseomatic_content \"><!-- [et_pb_line_break_holder] --><img alt=\"talento\"><!-- [et_pb_line_break_holder] --><img alt=\"talento\"><!-- [et_pb_line_break_holder] --><img alt=\"talento\"><!-- [et_pb_line_break_holder] --><img alt=\"talento\"><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><a href:\"https:\/\/tecnol.es\/\"><\/a><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><a href=\"https:\/\/www.instagram.com\/tqtecnol\/\" rel=\"follow\"><\/a><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><\/div><!-- [et_pb_line_break_holder] -->[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Uneix-te al #teamtecnol!EL QUE ENS DEFINEIXEl nostre dia a dia ens apassiona Tots sentim passi\u00f3 pel que fem. Ens sentim orgullosos del nostre treball i aix\u00f2 els nostres clients ho noten. Tenim l\u2019oportunitat d\u2019aprendre i formar-nos en all\u00f2 que realment ens apassiona i per aix\u00f2 som experts. Treballant a TECNOL tenim present que la nostra [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-13074","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Talent - TECNOL - GRUPO INDUSTRIAL GLOBAL<\/title>\n<meta name=\"description\" content=\"Formem equips d&#039;alt rendiment, amb talent, compromesos amb l&#039;excel\u00b7l\u00e8ncia i una visi\u00f3 \u00fanica de satisfacci\u00f3 al client.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tecnol.es\/ca\/talent\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Talent - TECNOL - GRUPO INDUSTRIAL GLOBAL\" \/>\n<meta property=\"og:description\" content=\"Formem equips d&#039;alt rendiment, amb talent, compromesos amb l&#039;excel\u00b7l\u00e8ncia i una visi\u00f3 \u00fanica de satisfacci\u00f3 al client.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tecnol.es\/ca\/talent\/\" \/>\n<meta property=\"og:site_name\" content=\"TECNOL - GRUPO INDUSTRIAL GLOBAL\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TQTecnol\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-26T10:16:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tecnol.es\/wp-content\/uploads\/2024\/04\/a136d6f2-ca25-4c5c-b50f-c976803a6e7d-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1342\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tecnol.es\/ca\/talent\/\",\"url\":\"https:\/\/tecnol.es\/ca\/talent\/\",\"name\":\"Talent - TECNOL - GRUPO INDUSTRIAL GLOBAL\",\"isPartOf\":{\"@id\":\"https:\/\/tecnol.es\/#website\"},\"datePublished\":\"2022-10-14T10:57:01+00:00\",\"dateModified\":\"2023-10-26T10:16:18+00:00\",\"description\":\"Formem equips d'alt rendiment, amb talent, compromesos amb l'excel\u00b7l\u00e8ncia i una visi\u00f3 \u00fanica de satisfacci\u00f3 al client.\",\"breadcrumb\":{\"@id\":\"https:\/\/tecnol.es\/ca\/talent\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tecnol.es\/ca\/talent\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tecnol.es\/ca\/talent\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/tecnol.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Talent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tecnol.es\/#website\",\"url\":\"https:\/\/tecnol.es\/\",\"name\":\"TECNOL - GRUPO INDUSTRIAL GLOBAL\",\"description\":\"Marca espa\u00f1ola l\u00edder en productos t\u00e9cnicos para la construcci\u00f3n y el mantenimiento urbano e industrial. M\u00e1s de 20 a\u00f1os de experiencia y m\u00e1s de 600 productos en nuestra web.\",\"publisher\":{\"@id\":\"https:\/\/tecnol.es\/#organization\"},\"alternateName\":\"Tecnol\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tecnol.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tecnol.es\/#organization\",\"name\":\"TECNOL - GRUPO INDUSTRIAL GLOBAL\",\"alternateName\":\"Tecnol\",\"url\":\"https:\/\/tecnol.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/tecnol.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tecnol.es\/wp-content\/uploads\/2024\/06\/Tecnol_GS.png\",\"contentUrl\":\"https:\/\/tecnol.es\/wp-content\/uploads\/2024\/06\/Tecnol_GS.png\",\"width\":829,\"height\":303,\"caption\":\"TECNOL - GRUPO INDUSTRIAL GLOBAL\"},\"image\":{\"@id\":\"https:\/\/tecnol.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/TQTecnol\",\"https:\/\/www.instagram.com\/tecnoltechnics\/\",\"https:\/\/www.linkedin.com\/company\/tq-tecnol-s-a-u\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Talent - TECNOL - GRUPO INDUSTRIAL GLOBAL","description":"Formem equips d'alt rendiment, amb talent, compromesos amb l'excel\u00b7l\u00e8ncia i una visi\u00f3 \u00fanica de satisfacci\u00f3 al client.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tecnol.es\/ca\/talent\/","og_locale":"ca_ES","og_type":"article","og_title":"Talent - TECNOL - GRUPO INDUSTRIAL GLOBAL","og_description":"Formem equips d'alt rendiment, amb talent, compromesos amb l'excel\u00b7l\u00e8ncia i una visi\u00f3 \u00fanica de satisfacci\u00f3 al client.","og_url":"https:\/\/tecnol.es\/ca\/talent\/","og_site_name":"TECNOL - GRUPO INDUSTRIAL GLOBAL","article_publisher":"https:\/\/www.facebook.com\/TQTecnol","article_modified_time":"2023-10-26T10:16:18+00:00","og_image":[{"width":1342,"height":1066,"url":"https:\/\/tecnol.es\/wp-content\/uploads\/2024\/04\/a136d6f2-ca25-4c5c-b50f-c976803a6e7d-1.jpg","type":"image\/jpeg"}],"twitter_misc":{"Temps estimat de lectura":"5 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tecnol.es\/ca\/talent\/","url":"https:\/\/tecnol.es\/ca\/talent\/","name":"Talent - TECNOL - GRUPO INDUSTRIAL GLOBAL","isPartOf":{"@id":"https:\/\/tecnol.es\/#website"},"datePublished":"2022-10-14T10:57:01+00:00","dateModified":"2023-10-26T10:16:18+00:00","description":"Formem equips d'alt rendiment, amb talent, compromesos amb l'excel\u00b7l\u00e8ncia i una visi\u00f3 \u00fanica de satisfacci\u00f3 al client.","breadcrumb":{"@id":"https:\/\/tecnol.es\/ca\/talent\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tecnol.es\/ca\/talent\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tecnol.es\/ca\/talent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tecnol.es\/"},{"@type":"ListItem","position":2,"name":"Talent"}]},{"@type":"WebSite","@id":"https:\/\/tecnol.es\/#website","url":"https:\/\/tecnol.es\/","name":"TECNOL - GRUPO INDUSTRIAL GLOBAL","description":"Marca espa\u00f1ola l\u00edder en productos t\u00e9cnicos para la construcci\u00f3n y el mantenimiento urbano e industrial. M\u00e1s de 20 a\u00f1os de experiencia y m\u00e1s de 600 productos en nuestra web.","publisher":{"@id":"https:\/\/tecnol.es\/#organization"},"alternateName":"Tecnol","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tecnol.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/tecnol.es\/#organization","name":"TECNOL - GRUPO INDUSTRIAL GLOBAL","alternateName":"Tecnol","url":"https:\/\/tecnol.es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/tecnol.es\/#\/schema\/logo\/image\/","url":"https:\/\/tecnol.es\/wp-content\/uploads\/2024\/06\/Tecnol_GS.png","contentUrl":"https:\/\/tecnol.es\/wp-content\/uploads\/2024\/06\/Tecnol_GS.png","width":829,"height":303,"caption":"TECNOL - GRUPO INDUSTRIAL GLOBAL"},"image":{"@id":"https:\/\/tecnol.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TQTecnol","https:\/\/www.instagram.com\/tecnoltechnics\/","https:\/\/www.linkedin.com\/company\/tq-tecnol-s-a-u\/"]}]}},"_links":{"self":[{"href":"https:\/\/tecnol.es\/ca\/wp-json\/wp\/v2\/pages\/13074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tecnol.es\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tecnol.es\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tecnol.es\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tecnol.es\/ca\/wp-json\/wp\/v2\/comments?post=13074"}],"version-history":[{"count":5,"href":"https:\/\/tecnol.es\/ca\/wp-json\/wp\/v2\/pages\/13074\/revisions"}],"predecessor-version":[{"id":17123,"href":"https:\/\/tecnol.es\/ca\/wp-json\/wp\/v2\/pages\/13074\/revisions\/17123"}],"wp:attachment":[{"href":"https:\/\/tecnol.es\/ca\/wp-json\/wp\/v2\/media?parent=13074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}